{"id":142621,"date":"2020-05-12T11:48:43","date_gmt":"2020-05-12T09:48:43","guid":{"rendered":"https:\/\/lediamant.ch\/produit\/uhren-de\/tissot-de\/tissot-t-sport-de\/tissot-supersport-de\/tissot-supersport-chrono-4\/"},"modified":"2026-08-12T15:22:00","modified_gmt":"2026-08-12T13:22:00","slug":"tissot-supersport-chrono-4","status":"publish","type":"product","link":"https:\/\/lediamant.ch\/de\/uhren\/142621-tissot-supersport-chrono-4\/","title":{"rendered":"Tissot Supersport Chrono 45.5mm"},"content":{"rendered":"<p>Die Tissot Supersport Chrono Kollektion ist perfekt f\u00fcr den modernen Gentleman, der seine Uhr im Alltag, B\u00fcro sowie bei sportlichen Ereignissen tragen m\u00f6chte. Die geraden Linien und scharfen Kanten in Kombination mit dem 45,5 mm Geh\u00e4use verleihen der Tissot Supersport Chrono eine starke Pers\u00f6nlichkeit. Die massiven Indizes mit SuperLuminova\u00ae Beschichtung sowie die asymmetrischen Applikationen auf dem Zifferblatt sorgen f\u00fcr einen kraftvollen 3D-Effekt, ein dynamisches Erscheinungsbild und erm\u00f6glichen eine beeindruckende Lesbarkeit bei Dunkelheit. Das handgen\u00e4hte Vintage-Lederarmband harmoniert mit der Uhr und verleiht dem Chronographen ein sportliches und trendiges Aussehen. Alle Modelle des Tissot Chrono Supersport haben ein massives 316L- Edelstahlgeh\u00e4use, kratzfestes Saphirglas und besitzen eine Wasserdichtigkeit bis zu einem Druck von 10 bar (100 Metern\/330 Fu\u00df). Diese Ausf\u00fchrung der Tissot Supersport Chrono besitzt ein Swiss-Made Quartzwerk sowie e<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Tissot Supersport Chrono Kollektion ist perfekt f\u00fcr den modernen Gentleman, der seine Uhr im Alltag, B\u00fcro sowie bei sportlichen Ereignissen tragen m\u00f6chte. Die geraden Linien und scharfen Kanten in Kombination mit dem 45,5 mm Geh\u00e4use verleihen der Tissot Supersport Chrono eine starke Pers\u00f6nlichkeit. Die massiven Indizes mit SuperLuminova\u00ae Beschichtung sowie die asymmetrischen Applikationen auf &#8230; <a title=\"Tissot Supersport Chrono 45.5mm\" class=\"read-more\" href=\"https:\/\/lediamant.ch\/de\/uhren\/142621-tissot-supersport-chrono-4\/\" aria-label=\"Mehr Informationen \u00fcber Tissot Supersport Chrono 45.5mm\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"featured_media":142603,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"27159","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"brand":[27087],"product_brand":[],"product_cat":[27159,27381,27203,27123],"product_tag":[],"class_list":["post-142621","product","type-product","status-publish","has-post-thumbnail","brand-tissot-de","product_cat-tissot-de","product_cat-tissot-supersport-chrono","product_cat-tissot-sport","product_cat-uhren","pa_couleurduboitier-grau-de","pa_couleurdubracelet-schwarz-de","pa_couleurducadran-schwarz","pa_dimensions-o-45-5-mm","pa_etancheite-100m-de","pa_forme-runden","pa_garantie-24monate","pa_genre-mann","pa_matiere-stahl","pa_matierebraceletmontre-leder","pa_mouvement-quarzbatterie-de","pa_swissmade-ja-de","pa_verre-saphir-de","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product\/142621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/media\/142603"}],"wp:attachment":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/media?parent=142621"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/brand?post=142621"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product_brand?post=142621"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product_cat?post=142621"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product_tag?post=142621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}