{"id":214337,"date":"2024-10-30T15:47:20","date_gmt":"2024-10-30T14:47:20","guid":{"rendered":"https:\/\/lediamant.ch\/?post_type=product&#038;p=214337"},"modified":"2024-10-30T15:48:46","modified_gmt":"2024-10-30T14:48:46","slug":"tissot-chemin-des-tourelles-automatic-chronograph-2","status":"publish","type":"product","link":"https:\/\/lediamant.ch\/de\/uhren\/214337-tissot-chemin-des-tourelles-automatic-chronograph-t1394621103800\/","title":{"rendered":"Tissot Chemin Des Tourelles Automatic Chronograph"},"content":{"rendered":"<p>Schlie\u00dfen Sie die Augen, denken Sie an eine reine Schweizer Uhr und Sie werden die Chemin des Tourelles sehen. Benannt nach der Stra\u00dfe, die zum Haus von Tissot in den Schweizer Bergen f\u00fchrt, ist sie die Ikone von Tissot: rund, klassisch, mechanisch, zeitlos. Diese aktualisierte und raffinierte Edition ist mit einem leicht gew\u00f6lbten Saphirglas ausgestattet, das ein Zifferblatt mit einfachen und eleganten Stabindexen bedeckt, die jeweils facettiert sind, um das Licht auf diskrete und dennoch raffinierte Weise einzufangen. Unter diesem Zifferblatt befindet sich ein Valjoux A05.231 Uhrwerk, ein automatisches Spitzenwerk mit einer Gangreserve von 68 Stunden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schlie\u00dfen Sie die Augen, denken Sie an eine reine Schweizer Uhr und Sie werden die Chemin des Tourelles sehen. Benannt nach der Stra\u00dfe, die zum Haus von Tissot in den Schweizer Bergen f\u00fchrt, ist sie die Ikone von Tissot: rund, klassisch, mechanisch, zeitlos. Diese aktualisierte und raffinierte Edition ist mit einem leicht gew\u00f6lbten Saphirglas ausgestattet, &#8230; <a title=\"Tissot Chemin Des Tourelles Automatic Chronograph\" class=\"read-more\" href=\"https:\/\/lediamant.ch\/de\/uhren\/214337-tissot-chemin-des-tourelles-automatic-chronograph-t1394621103800\/\" aria-label=\"Mehr Informationen \u00fcber Tissot Chemin Des Tourelles Automatic Chronograph\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"featured_media":214330,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"%%post_title%%","_seopress_titles_desc":"Eleganz und Schweizer Pr\u00e4zision mit der Tissot Chemin des Tourelles Uhr. Ein klassisches Design, ein fortschrittliches Automatikwerk f\u00fcr zeitlose Raffinesse.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"27245","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":{"210527":{"rich_snippets_lb":{"opening_hours":[{"am":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}},"pm":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}}},{"am":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}},"pm":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}}},{"am":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}},"pm":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}}},{"am":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}},"pm":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}}},{"am":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}},"pm":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}}},{"am":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}},"pm":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}}},{"am":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}},"pm":{"start":{"hours":"00","mins":"00"},"end":{"hours":"00","mins":"00"}}}]}}}},"brand":[27087],"product_brand":[],"product_cat":[27123,27159,27245,27489],"product_tag":[],"class_list":["post-214337","product","type-product","status-publish","has-post-thumbnail","brand-tissot-de","product_cat-uhren","product_cat-tissot-de","product_cat-tissot-classic","product_cat-tissot-chemin-des-tourelles","pa_couleurduboitier-grau-de","pa_couleurdubracelet-grau-de","pa_couleurducadran-silber","pa_dimensions-o-42-mm","pa_etancheite-50m-de","pa_forme-runden","pa_garantie-24monate","pa_genre-mann","pa_matiere-stahl","pa_matierebraceletmontre-edelstahl","pa_mouvement-automatik-de","pa_swissmade-ja-de","pa_typedemontre-chronograph-de","pa_verre-saphir-de","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product\/214337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/media\/214330"}],"wp:attachment":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/media?parent=214337"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/brand?post=214337"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product_brand?post=214337"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product_cat?post=214337"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product_tag?post=214337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}