{"id":219901,"date":"2025-09-26T13:39:46","date_gmt":"2025-09-26T11:39:46","guid":{"rendered":"https:\/\/lediamant.ch\/produit\/unkategorisiert\/balmain-classic-r-41-mm-9\/"},"modified":"2025-09-26T15:34:34","modified_gmt":"2025-09-26T13:34:34","slug":"balmain-classic-r-41-mm-9","status":"publish","type":"product","link":"https:\/\/lediamant.ch\/de\/uhren\/219901-balmain-classic-r-41-mm-b41003161\/","title":{"rendered":"Balmain Classic R 41mm"},"content":{"rendered":"<p>Die Balmain Classic R ist eine anspruchsvolle Herrenuhr mit modernem Design, inspiriert von der Pariser Haute Couture. inspiriert von der Pariser Haute Couture. Das mittelgraue Zifferblatt und die modernen r\u00f6mischen Ziffern Das mittelgraue Zifferblatt und die modernen r\u00f6mischen Ziffern verleihen der Uhr einen Hauch von Selbstbewusstsein und Raffinesse, w\u00e4hrend das 41 mm Gelbgold PVD-Geh\u00e4use mit seinem eleganten 7,17 mm Profil und dem passenden Armband Eleganz f\u00fcr jeden Tag verspricht. Dieser Zeitmesser ist Swiss Made. Dieser Swiss Made Zeitmesser ist mit einem Saphirglas ausgestattet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Balmain Classic R ist eine anspruchsvolle Herrenuhr mit modernem Design, inspiriert von der Pariser Haute Couture. inspiriert von der Pariser Haute Couture. Das mittelgraue Zifferblatt und die modernen r\u00f6mischen Ziffern Das mittelgraue Zifferblatt und die modernen r\u00f6mischen Ziffern verleihen der Uhr einen Hauch von Selbstbewusstsein und Raffinesse, w\u00e4hrend das 41 mm Gelbgold PVD-Geh\u00e4use mit &#8230; <a title=\"Balmain Classic R 41mm\" class=\"read-more\" href=\"https:\/\/lediamant.ch\/de\/uhren\/219901-balmain-classic-r-41-mm-b41003161\/\" aria-label=\"Mehr Informationen \u00fcber Balmain Classic R 41mm\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"featured_media":219812,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"Die Balmain Classic R, ein Schweizer Werk mit grauem Zifferblatt und PVD-Goldgeh\u00e4use, ist die perfekte Verbindung von Modernit\u00e4t und Pariser Eleganz.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"27173","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":{"210527":{"rich_snippets_lb":{"opening_hours":[{"am":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}},"pm":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}}},{"am":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}},"pm":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}}},{"am":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}},"pm":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}}},{"am":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}},"pm":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}}},{"am":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}},"pm":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}}},{"am":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}},"pm":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}}},{"am":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}},"pm":{"start":{"hours":"0","mins":"0"},"end":{"hours":"0","mins":"0"}}}]}}}},"brand":[27083],"product_brand":[],"product_cat":[27123,27173,27433],"product_tag":[],"class_list":["post-219901","product","type-product","status-publish","has-post-thumbnail","brand-balmain-de","product_cat-uhren","product_cat-balmain-de","product_cat-classic-r-de","pa_couleurduboitier-gelb-de","pa_couleurdubracelet-gelb-de","pa_couleurducadran-grau","pa_etancheite-50m-de","pa_forme-runden","pa_genre-mann","pa_matiere-gelbgoldpvd","pa_matierebraceletmontre-edelstahl","pa_mouvement-quarzbatterie-de","pa_swissmade-ja-de","pa_verre-saphir-de","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product\/219901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/media\/219812"}],"wp:attachment":[{"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/media?parent=219901"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/brand?post=219901"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product_brand?post=219901"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product_cat?post=219901"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lediamant.ch\/de\/wp-json\/wp\/v2\/product_tag?post=219901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}